{"id":559,"date":"2022-04-04T10:48:38","date_gmt":"2022-04-04T10:48:38","guid":{"rendered":"https:\/\/ieditorial.net\/blog-elearning\/?p=559"},"modified":"2022-04-04T11:12:13","modified_gmt":"2022-04-04T11:12:13","slug":"contrato-de-formacion-en-alternancia","status":"publish","type":"post","link":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/","title":{"rendered":"Contrato de Formaci\u00f3n en Alternancia"},"content":{"rendered":"\n<h2>\u00bfCu\u00e1l es la principal novedad?<\/h2>\n<p>Ahora puedes realizar la <strong>formaci\u00f3n en alternancia<\/strong> (antiguo <em>contrato para la formaci\u00f3n y el aprendizaje<\/em>) con <a href=\"https:\/\/ieditorial.net\/4626-especialidades-formativas\">ESPECIALIDADES FORMATIVAS<\/a> y no solo con <a href=\"https:\/\/ieditorial.net\/contenido\/85-certificados-de-profesionalidad\">Certificados de Profesionalidad<\/a> como hasta ahora.<\/p>\n<p><a href=\"https:\/\/ieditorial.net\/\">iEditorial<\/a> dispone del mayor cat\u00e1logo de <strong>Especialidades Formativas<\/strong> (m\u00e1s de 1.800 t\u00edtulos) para que afrontes este nuevo cambio con las mejores perspectivas.<\/p>\n<h2>\u00bfQu\u00e9 es el Contrato de Formaci\u00f3n en Alternancia?<\/h2>\n<p>Desde el <strong>31 de marzo de 2022<\/strong> ha entrado en vigor la reforma laboral por la que se modifican los contratos formativos, reguladas por Real Decreto-ley 32\/2021 de 28 de diciembre.<\/p>\n<p>El <strong>contrato de formaci\u00f3n en alternancia<\/strong> sustituye el antiguo contrato para la formaci\u00f3n y el aprendizaje, vi\u00e9ndose afectados aquellos contratos en los que se acogen los <strong>certificados de profesionalidad y especialidades formativas<\/strong>.<\/p>\n<p>El contrato de formaci\u00f3n en alternancia permite compatibilizar la formaci\u00f3n con la actividad laboral retribuida. Es aplicable en el \u00e1mbito de la formaci\u00f3n profesional, los estudios universitarios o el Cat\u00e1logo de especialidades formativas del Sistema Nacional de Empleo.<\/p>\n<h3>\u00bfCu\u00e1les son las principales caracter\u00edsticas?<\/h3>\n<ul>\n<li>Se podr\u00e1 celebrar <strong>con personas que carezcan de cualificaci\u00f3n profesional reconocida<\/strong> por las titulaciones o certificados requeridos. Se podr\u00e1n realizar contratos vinculados a estudios de formaci\u00f3n profesional o universitaria con personas que posean otra titulaci\u00f3n siempre que no haya tenido otro contrato formativo previo en una formaci\u00f3n del mismo nivel formativo y del mismo sector productivo.<\/li>\n<li>Para los <strong>certificados de profesionalidad de nivel 1 y 2<\/strong>, y programas\u00a0 de formaci\u00f3n en alternancia <strong>que formen parte del Cat\u00e1logo de especialidades formativas<\/strong> del Sistema Nacional de Empleo, el contrato solo se podr\u00e1 formalizar para <strong>personas de hasta treinta a\u00f1os<\/strong>. Para las personas con discapacidad no habr\u00e1 l\u00edmite de edad.<\/li>\n<li>La <strong>actividad<\/strong> desempe\u00f1ada por la persona trabajadora en la empresa deber\u00e1 estar <strong>directamente relacionada con las actividades formativas<\/strong> que justifican la contrataci\u00f3n laboral.<\/li>\n<li>La <strong>duraci\u00f3n del contrato<\/strong> ser\u00e1 de un m\u00ednimo de <strong>tres meses y un m\u00e1ximo de dos a\u00f1os<\/strong>.<\/li>\n<li><strong>La retribuci\u00f3n ser\u00e1 la establecida en el convenio colectivo<\/strong> de aplicaci\u00f3n.<\/li>\n<li>Las <strong>situaciones de incapacidad temporal<\/strong>, nacimiento, adopci\u00f3n, guarda con fines de adopci\u00f3n, acogimiento, riesgo durante el embarazo, riesgo durante la lactancia y violencia de g\u00e9nero <strong>interrumpir\u00e1n el c\u00f3mputo de la duraci\u00f3n del contrato.<\/strong><\/li>\n<\/ul>\n<h3>\u00bfQu\u00e9 deben saber los centros de formaci\u00f3n?<\/h3>\n<ul>\n<li>La persona contratada contar\u00e1 con una <strong>persona tutora<\/strong> designada por el centro o entidad de formaci\u00f3n y otra designada por la empresa.<\/li>\n<li>Los <strong>centros de formaci\u00f3n profesional<\/strong>, las entidades formativas acreditadas o inscritas y los centros universitarios, <strong>elaborar\u00e1n<\/strong> con la participaci\u00f3n de la empresa los <strong>planes formativos individuales<\/strong> donde se especifique el contenido de la formaci\u00f3n, el calendario y las actividades y requisitos de tutor\u00eda para el cumplimiento de sus objetivos.<\/li>\n<li>Solo podr\u00e1 celebrarse <strong>un contrato de formaci\u00f3n en alternancia por cada ciclo formativo<\/strong> de formaci\u00f3n profesional y titulaci\u00f3n universitaria, certificado de profesionalidad o itinerario de especialidades formativas del Cat\u00e1logo de Especialidades Formativas del Sistema Nacional de Empleo. <strong style=\"font-size: inherit;\">Podr\u00e1n formalizarse contratos de formaci\u00f3n en alternancia con varias empresas<\/strong><span style=\"font-size: inherit;\"> para el mismo ciclo, certificado de profesionalidad o itinerario de especialidades del Cat\u00e1logo, siempre que los contratos respondan a distintas actividades vinculadas al ciclo y sin que la duraci\u00f3n m\u00e1xima de todos los contratos exceda la duraci\u00f3n m\u00e1xima de dos a\u00f1os.<\/span><\/li>\n<\/ul>\n<h3>Aspectos a tener en cuenta en la Formaci\u00f3n en Alternancia<\/h3>\n<ul>\n<li>El <strong>tiempo de trabajo efectivo<\/strong> no podr\u00e1 ser superior al 65 por ciento durante el primer a\u00f1o, o al 85 por ciento durante el segundo.<\/li>\n<li><strong>No se podr\u00e1n celebrar contratos formativos en alternancia<\/strong> <strong>cuando la actividad<\/strong> o puesto de trabajo correspondiente al contrato <strong>haya sido desempe\u00f1ado con anterioridad<\/strong> por la persona trabajadora en la misma empresa.<\/li>\n<li>Las <strong>personas contratadas<\/strong> con contrato de formaci\u00f3n en alternancia <strong>no podr\u00e1n realizar horas complementarias ni horas extraordinarias<\/strong>.<\/li>\n<li><strong>No podr\u00e1 establecerse periodo de prueba<\/strong> en estos contratos.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p> [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":2,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[5],"tags":[],"class_list":["post-559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial<\/title>\n<meta name=\"description\" content=\"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\/2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial\" \/>\n<meta property=\"og:description\" content=\"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\/2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ieditorial\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-04T10:48:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-04T11:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#\\\/schema\\\/person\\\/7896ed5e9c457701608b4c81a4b0e252\"},\"headline\":\"Contrato de Formaci\u00f3n en Alternancia\",\"datePublished\":\"2022-04-04T10:48:38+00:00\",\"dateModified\":\"2022-04-04T11:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/\"},\"wordCount\":679,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/contratos-formativos-en-alternancia.jpg\",\"articleSection\":[\"Formaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/\",\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/\",\"name\":\"Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/contratos-formativos-en-alternancia.jpg\",\"datePublished\":\"2022-04-04T10:48:38+00:00\",\"dateModified\":\"2022-04-04T11:12:13+00:00\",\"description\":\"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\\\/2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/contratos-formativos-en-alternancia.jpg\",\"contentUrl\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/contratos-formativos-en-alternancia.jpg\",\"width\":995,\"height\":579,\"caption\":\"Contratos formativos en alternancia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/contrato-de-formacion-en-alternancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n\",\"item\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/formacion\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Contrato de Formaci\u00f3n en Alternancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#website\",\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/\",\"name\":\"Blog Ieditorial\",\"description\":\"Blog de iEditorial\",\"publisher\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#organization\",\"name\":\"iEditorial\",\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo_ieditorial.png\",\"contentUrl\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo_ieditorial.png\",\"width\":133,\"height\":60,\"caption\":\"iEditorial\"},\"image\":{\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/#\\\/schema\\\/person\\\/7896ed5e9c457701608b4c81a4b0e252\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/ieditorial.net\\\/blog-ieditorial\"],\"url\":\"https:\\\/\\\/ieditorial.net\\\/blog-elearning\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial","description":"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\/2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/","og_locale":"es_ES","og_type":"article","og_title":"Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial","og_description":"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\/2021.","og_url":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/","og_site_name":"Blog Ieditorial","article_published_time":"2022-04-04T10:48:38+00:00","article_modified_time":"2022-04-04T11:12:13+00:00","og_image":[{"width":995,"height":579,"url":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#article","isPartOf":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/"},"author":{"name":"admin","@id":"https:\/\/ieditorial.net\/blog-elearning\/#\/schema\/person\/7896ed5e9c457701608b4c81a4b0e252"},"headline":"Contrato de Formaci\u00f3n en Alternancia","datePublished":"2022-04-04T10:48:38+00:00","dateModified":"2022-04-04T11:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/"},"wordCount":679,"commentCount":0,"publisher":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/#organization"},"image":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#primaryimage"},"thumbnailUrl":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg","articleSection":["Formaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/","url":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/","name":"Contrato de Formaci\u00f3n en Alternancia | Blog Ieditorial","isPartOf":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#primaryimage"},"image":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#primaryimage"},"thumbnailUrl":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg","datePublished":"2022-04-04T10:48:38+00:00","dateModified":"2022-04-04T11:12:13+00:00","description":"Los centros de formaci\u00f3n pueden realizar la formaci\u00f3n en alternancia con la entrada en vigor de la reforma laboral regulada por Real Decreto-ley 32\/2021.","breadcrumb":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#primaryimage","url":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg","contentUrl":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2022\/04\/contratos-formativos-en-alternancia.jpg","width":995,"height":579,"caption":"Contratos formativos en alternancia"},{"@type":"BreadcrumbList","@id":"https:\/\/ieditorial.net\/blog-elearning\/contrato-de-formacion-en-alternancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/ieditorial.net\/blog-elearning\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n","item":"https:\/\/ieditorial.net\/blog-elearning\/formacion\/"},{"@type":"ListItem","position":3,"name":"Contrato de Formaci\u00f3n en Alternancia"}]},{"@type":"WebSite","@id":"https:\/\/ieditorial.net\/blog-elearning\/#website","url":"https:\/\/ieditorial.net\/blog-elearning\/","name":"Blog Ieditorial","description":"Blog de iEditorial","publisher":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ieditorial.net\/blog-elearning\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ieditorial.net\/blog-elearning\/#organization","name":"iEditorial","url":"https:\/\/ieditorial.net\/blog-elearning\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ieditorial.net\/blog-elearning\/#\/schema\/logo\/image\/","url":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2020\/05\/logo_ieditorial.png","contentUrl":"https:\/\/ieditorial.net\/blog-elearning\/wp-content\/uploads\/2020\/05\/logo_ieditorial.png","width":133,"height":60,"caption":"iEditorial"},"image":{"@id":"https:\/\/ieditorial.net\/blog-elearning\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ieditorial.net\/blog-elearning\/#\/schema\/person\/7896ed5e9c457701608b4c81a4b0e252","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44d4998b7761317afb6a1f680c3297603f0c22e29aeb710aeb2b1ab779994305?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/ieditorial.net\/blog-ieditorial"],"url":"https:\/\/ieditorial.net\/blog-elearning\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/posts\/559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/comments?post=559"}],"version-history":[{"count":5,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/posts\/559\/revisions"}],"predecessor-version":[{"id":568,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/posts\/559\/revisions\/568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/media\/569"}],"wp:attachment":[{"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/media?parent=559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/categories?post=559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ieditorial.net\/blog-elearning\/wp-json\/wp\/v2\/tags?post=559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}